{"id":13303,"date":"2021-12-28T02:29:00","date_gmt":"2021-12-28T06:29:00","guid":{"rendered":"https:\/\/www.pedroandretta.info\/index\/2021\/12\/28\/a-pressao-para-banir-livros-nas-escolas-do-texas-se-espalha-para-as-bibliotecas\/"},"modified":"2021-12-28T02:29:00","modified_gmt":"2021-12-28T06:29:00","slug":"a-pressao-para-banir-livros-nas-escolas-do-texas-se-espalha-para-as-bibliotecas","status":"publish","type":"post","link":"https:\/\/www.pedroandretta.info\/index\/2021\/12\/a-pressao-para-banir-livros-nas-escolas-do-texas-se-espalha-para-as-bibliotecas\/","title":{"rendered":"A press\u00e3o para banir livros nas escolas do Texas se espalha para as bibliotecas &#8230;"},"content":{"rendered":"<p>[ad_1]<br \/>\n<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/thumbnails.texastribune.org\/OXLsZNu2WHHb71N3PvFB5ZJ2U1k%3D\/1200x630\/filters%3Aquality%2895%29\/static.texastribune.org\/media\/files\/cc7a2f5b7d37663d11a659deb8b6d283\/Llano%20Public%20Library%20SF%20TT%2019.jpg?w=696&#038;ssl=1\"\/><\/p>\n<p>A press\u00e3o para banir livros nas escolas do Texas se espalha para as bibliotecas p\u00fablicas l&#8221;Alguns residentes do Texas est\u00e3o pedindo mais voz sobre os t\u00edtulos que aparecem nas prateleiras das bibliotecas p\u00fablicas&#8221;\ud83d\ude44 #Censura #Diversidade \ud83c\uddfa\ud83c\uddf8via Texas Tribune <a href=\"https:\/\/www.texastribune.org\/2021\/12\/20\/texas-library-books\/\" target=\"_blank\" rel=\"noopener\">texastribune.org\/2021\/12\/20\/tex\u2026<\/a><br \/>\n[ad_2]<br \/>\n<br \/>Curadoria: <a href=\"https:\/\/t.co\/qdDIov5LTC\">Projeto Informe-CI<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A press\u00e3o para banir livros nas escolas do Texas se espalha para as bibliotecas p\u00fablicas l&#8221;Alguns residentes do Texas est\u00e3o pedindo mais voz sobre os t\u00edtulos que aparecem nas prateleiras das bibliotecas p\u00fablicas&#8221;\ud83d\ude44 #Censura #Diversidade \ud83c\uddfa\ud83c\uddf8via Texas Tribune texastribune.org\/2021\/12\/20\/tex\u2026 [ad_2] Curadoria: Projeto Informe-CI<\/p>\n","protected":false},"author":1,"featured_media":13304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[168,304],"class_list":["post-13303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informeci","tag-censura","tag-diversidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2021\/12\/Llano-Public-Library-SF-TT-19.jpg?fit=1200%2C630&ssl=1","views":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/13303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/comments?post=13303"}],"version-history":[{"count":0,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/13303\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/media\/13304"}],"wp:attachment":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/media?parent=13303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/categories?post=13303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/tags?post=13303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}