{"id":17684,"date":"2022-11-18T14:23:31","date_gmt":"2022-11-18T18:23:31","guid":{"rendered":"https:\/\/www.pedroandretta.info\/index\/2022\/11\/18\/autoria-ordem-de-autoria-e-contribuicao-de-autor-l-a-identificacao-das-v\/"},"modified":"2022-11-18T14:23:31","modified_gmt":"2022-11-18T18:23:31","slug":"autoria-ordem-de-autoria-e-contribuicao-de-autor-l-a-identificacao-das-v","status":"publish","type":"post","link":"https:\/\/www.pedroandretta.info\/index\/2022\/11\/autoria-ordem-de-autoria-e-contribuicao-de-autor-l-a-identificacao-das-v\/","title":{"rendered":"Autoria, ordem de autoria e contribui\u00e7\u00e3o de autor l &#8220;[&#8230;] a identifica\u00e7\u00e3o das v&#8230;"},"content":{"rendered":"<p>[ad_1]<br \/>\n<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/pbs.twimg.com\/media\/Fh3avDbXkAElO-i.png?w=696&#038;ssl=1\" \/><\/p>\n<p>Autoria, ordem de autoria e contribui\u00e7\u00e3o de autor l &#8220;[&#8230;] a identifica\u00e7\u00e3o das v\u00e1rias tipologias de autoria existentes (convidada, presenteada, honor\u00e1ria, incompleta, injustificada, descart\u00e1vel, \u00f3rf\u00e3 e forjada),  tamb\u00e9m v\u00eam ganhando destaque.&#8221; #Autoria <a href=\"https:\/\/periodicos.sbu.unicamp.br\/ojs\/index.php\/rdbci\/article\/view\/8669142\" target=\"_blank\" rel=\"noopener\">periodicos.sbu.unicamp.br\/ojs\/index.php\/\u2026<\/a> <a href=\"https:\/\/t.co\/EkT97qHTOJ\" target=\"_blank\" rel=\"noopener\">https:\/\/t.co\/EkT97qHTOJ<\/a><br \/>\n[ad_2]<br \/>\n<br \/>Curadoria: <a href=\"https:\/\/t.co\/qdDIov5LTC\">Projeto Informe-CI<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Autoria, ordem de autoria e contribui\u00e7\u00e3o de autor l &#8220;[&#8230;] a identifica\u00e7\u00e3o das v\u00e1rias tipologias de autoria existentes (convidada, presenteada, honor\u00e1ria, incompleta, injustificada, descart\u00e1vel, \u00f3rf\u00e3 e forjada), tamb\u00e9m v\u00eam ganhando destaque.&#8221; #Autoria periodicos.sbu.unicamp.br\/ojs\/index.php\/\u2026 https:\/\/t.co\/EkT97qHTOJ [ad_2] Curadoria: Projeto Informe-CI<\/p>\n","protected":false},"author":1,"featured_media":17685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[445],"class_list":["post-17684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informeci","tag-autoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2022\/11\/Fh3avDbXkAElO-i.png?fit=511%2C741&ssl=1","views":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/17684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/comments?post=17684"}],"version-history":[{"count":0,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/17684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/media\/17685"}],"wp:attachment":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/media?parent=17684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/categories?post=17684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/tags?post=17684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}