{"id":21027,"date":"2023-08-12T11:12:41","date_gmt":"2023-08-12T15:12:41","guid":{"rendered":"https:\/\/www.pedroandretta.info\/index\/2023\/08\/12\/conselho-da-ifla-decide-sobre-wlic-2024-l-68-viraram-contra-a-realizacao-do-if\/"},"modified":"2023-08-12T11:12:41","modified_gmt":"2023-08-12T15:12:41","slug":"conselho-da-ifla-decide-sobre-wlic-2024-l-68-viraram-contra-a-realizacao-do-if","status":"publish","type":"post","link":"https:\/\/www.pedroandretta.info\/index\/2023\/08\/conselho-da-ifla-decide-sobre-wlic-2024-l-68-viraram-contra-a-realizacao-do-if\/","title":{"rendered":"Conselho da IFLA decide sobre WLIC 2024 l \u201c68% viraram contra a realiza\u00e7\u00e3o do IF&#8230;"},"content":{"rendered":"<p>[ad_1]<br \/>\nConselho da IFLA decide sobre WLIC 2024 l \u201c68% viraram contra a realiza\u00e7\u00e3o do IFLA WLIC 2024 em Dubai e 27% a favor (votos ponderados). Enquanto a maioria dos eleitores da Europa, Am\u00e9rica do Norte e Am\u00e9rica Latina e Caribe votou contra [\u2026].\u201d \ud83c\uddfa\ud83c\uddf8 via LTG  <a target=\"_blank\" href=\"https:\/\/librarytechnology.org\/pr\/29108\" rel=\"noopener\">librarytechnology.org\/pr\/29108<\/a><br \/>\n[ad_2]<br \/>\n<br \/>Acesse o item em: <a href=\"https:\/\/librarytechnology.org\/pr\/29108\">https:\/\/librarytechnology.org\/pr\/29108<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Conselho da IFLA decide sobre WLIC 2024 l \u201c68% viraram contra a realiza\u00e7\u00e3o do IFLA WLIC 2024 em Dubai e 27% a favor (votos ponderados). Enquanto a maioria dos eleitores da Europa, Am\u00e9rica do Norte e Am\u00e9rica Latina e Caribe votou contra [\u2026].\u201d \ud83c\uddfa\ud83c\uddf8 via LTG librarytechnology.org\/pr\/29108 [ad_2] Acesse o item em: https:\/\/librarytechnology.org\/pr\/29108<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-21027","post","type-post","status-publish","format-standard","hentry","category-informeci"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","views":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/21027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/comments?post=21027"}],"version-history":[{"count":0,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/21027\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/media?parent=21027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/categories?post=21027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/tags?post=21027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}