{"id":24033,"date":"2024-03-10T01:27:23","date_gmt":"2024-03-10T05:27:23","guid":{"rendered":"https:\/\/www.pedroandretta.info\/index\/?p=24033"},"modified":"2024-03-10T01:27:47","modified_gmt":"2024-03-10T05:27:47","slug":"biblioteca-nacional-lancara-na-proxima-quarta-feira-13-catalogo-digital-sobre-acervo-de-percival-farquhar","status":"publish","type":"post","link":"https:\/\/www.pedroandretta.info\/index\/2024\/03\/biblioteca-nacional-lancara-na-proxima-quarta-feira-13-catalogo-digital-sobre-acervo-de-percival-farquhar\/","title":{"rendered":"Biblioteca Nacional lan\u00e7ar\u00e1, na pr\u00f3xima quarta-feira (13), cat\u00e1logo digital sobre acervo de Percival Farquhar"},"content":{"rendered":"\n<p><strong>Biblioteca Nacional lan\u00e7ar\u00e1, na pr\u00f3xima quarta-feira (13), cat\u00e1logo digital sobre acervo de Percival Farquhar<\/strong><\/p>\n\n\n\n<p>Nascido em 19 de outubro de 1864 na cidade de York, no estado da Pensilv\u00e2nia (EUA), Percival Farquhar era filho de filho de Arthur Briggs Farquhar, um industrial milion\u00e1rio, e Elizabeth Newbold Jessup. Formado em Engenharia pela Universidade de Yale, iniciou suas atividades empresariais no Brasil em 1904. Ao longo da 1\u00aa metade do s\u00e9culo XX, fundou diversas empresas, obtendo concess\u00f5es para atuar nos ramos da de siderurgia, minera\u00e7\u00e3o, ferrovias, hidrel\u00e9tricas, constru\u00e7\u00e3o de portos e vias de transportes.<\/p>\n\n\n\n<p>#BN #Rond\u00f4nia #FontesDeInforma\u00e7\u00e3o<\/p>\n\n\n\n<p>via BN<\/p>\n\n\n\n<p>Dispon\u00edvel em: <a href=\"https:\/\/www.gov.br\/bn\/pt-br\/central-de-conteudos\/noticias\/biblioteca-nacional-lancara-na-proxima-quarta-feira-catalogo-digital-sobre-acervo-de-percival-farquhar\">https:\/\/www.gov.br\/bn\/pt-br\/central-de-conteudos\/noticias\/biblioteca-nacional-lancara-na-proxima-quarta-feira-catalogo-digital-sobre-acervo-de-percival-farquhar<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"600\" height=\"255\" src=\"https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2024\/03\/image-27.png?resize=600%2C255&#038;ssl=1\" alt=\"\" class=\"wp-image-24034\" srcset=\"https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2024\/03\/image-27.png?resize=600%2C255&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2024\/03\/image-27.png?resize=300%2C128&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2024\/03\/image-27.png?w=768&amp;ssl=1 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Biblioteca Nacional lan\u00e7ar\u00e1, na pr\u00f3xima quarta-feira (13), cat\u00e1logo digital sobre acervo de Percival Farquhar Nascido em 19 de outubro de 1864 na cidade de York, no estado da Pensilv\u00e2nia (EUA), Percival Farquhar era filho de filho de Arthur Briggs Farquhar, um industrial milion\u00e1rio, e Elizabeth Newbold Jessup. Formado em Engenharia pela Universidade de Yale, iniciou<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/www.pedroandretta.info\/index\/2024\/03\/biblioteca-nacional-lancara-na-proxima-quarta-feira-13-catalogo-digital-sobre-acervo-de-percival-farquhar\/\" class=\"home-blog-btn\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[402,133,239],"class_list":["post-24033","post","type-post","status-publish","format-standard","hentry","category-informeci","tag-bibliotecanacional","tag-fontesdeinformacao","tag-rondonia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","views":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/24033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/comments?post=24033"}],"version-history":[{"count":0,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/24033\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/media?parent=24033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/categories?post=24033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/tags?post=24033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}