{"id":25371,"date":"2024-06-18T09:27:02","date_gmt":"2024-06-18T13:27:02","guid":{"rendered":"https:\/\/www.pedroandretta.info\/index\/?p=25371"},"modified":"2024-06-18T09:27:07","modified_gmt":"2024-06-18T13:27:07","slug":"mais-da-metade-dos-alunos-brasileiros-tem-nivel-baixo-de-criatividade-pais-esta-entre-os-ultimos-de-ranking-internacional-diz-pisa","status":"publish","type":"post","link":"https:\/\/www.pedroandretta.info\/index\/2024\/06\/mais-da-metade-dos-alunos-brasileiros-tem-nivel-baixo-de-criatividade-pais-esta-entre-os-ultimos-de-ranking-internacional-diz-pisa\/","title":{"rendered":"Mais da metade dos alunos brasileiros tem n\u00edvel baixo de criatividade; pa\u00eds est\u00e1 entre os \u00faltimos de ranking internacional, diz Pisa"},"content":{"rendered":"\n<p><strong>Mais da metade dos alunos brasileiros tem n\u00edvel baixo de criatividade; pa\u00eds est\u00e1 entre os \u00faltimos de ranking internacional, diz Pisa<\/strong><\/p>\n\n\n\n<p>Mais da metade (54,3%) dos alunos brasileiros de 15 anos apresentou um baixo n\u00edvel de criatividade ao tentar solucionar problemas sociais e cient\u00edficos apresentados em uma prova internacional de conhecimentos. O dado foi divulgado nesta ter\u00e7a-feira (18) pela Organiza\u00e7\u00e3o para a Coopera\u00e7\u00e3o e Desenvolvimento Econ\u00f4mico (OCDE).<\/p>\n\n\n\n<p>#Criatividade #PISA<\/p>\n\n\n\n<p>via G1<\/p>\n\n\n\n<p>Dispon\u00edvel em: <a href=\"https:\/\/g1.globo.com\/educacao\/noticia\/2024\/06\/18\/mais-da-metade-dos-alunos-brasileiros-tem-nivel-baixo-de-criatividade-pais-esta-entre-os-ultimos-de-ranking-internacional-diz-pisa.ghtml\">https:\/\/g1.globo.com\/educacao\/noticia\/2024\/06\/18\/mais-da-metade-dos-alunos-brasileiros-tem-nivel-baixo-de-criatividade-pais-esta-entre-os-ultimos-de-ranking-internacional-diz-pisa.ghtml<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"435\" height=\"429\" src=\"https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2024\/06\/image-59.png?resize=435%2C429&#038;ssl=1\" alt=\"\" class=\"wp-image-25372\" srcset=\"https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2024\/06\/image-59.png?w=435&amp;ssl=1 435w, https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2024\/06\/image-59.png?resize=300%2C296&amp;ssl=1 300w\" sizes=\"(max-width: 435px) 100vw, 435px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Mais da metade dos alunos brasileiros tem n\u00edvel baixo de criatividade; pa\u00eds est\u00e1 entre os \u00faltimos de ranking internacional, diz Pisa Mais da metade (54,3%) dos alunos brasileiros de 15 anos apresentou um baixo n\u00edvel de criatividade ao tentar solucionar problemas sociais e cient\u00edficos apresentados em uma prova internacional de conhecimentos. O dado foi divulgado<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/www.pedroandretta.info\/index\/2024\/06\/mais-da-metade-dos-alunos-brasileiros-tem-nivel-baixo-de-criatividade-pais-esta-entre-os-ultimos-de-ranking-internacional-diz-pisa\/\" class=\"home-blog-btn\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[172,1415],"class_list":["post-25371","post","type-post","status-publish","format-standard","hentry","category-informeci","tag-criatividade","tag-pisa"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","views":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/25371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/comments?post=25371"}],"version-history":[{"count":0,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/25371\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/media?parent=25371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/categories?post=25371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/tags?post=25371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}