{"id":28833,"date":"2025-01-24T12:56:30","date_gmt":"2025-01-24T16:56:30","guid":{"rendered":"https:\/\/www.pedroandretta.info\/index\/?p=28833"},"modified":"2025-01-24T12:56:34","modified_gmt":"2025-01-24T16:56:34","slug":"19a-gestao-do-cfb-lanca-biblioteca-na-escola-e-a-lei-12-244-2010-mapeamento-da-producao-cientifica-e-academica-cfb","status":"publish","type":"post","link":"https:\/\/www.pedroandretta.info\/index\/2025\/01\/19a-gestao-do-cfb-lanca-biblioteca-na-escola-e-a-lei-12-244-2010-mapeamento-da-producao-cientifica-e-academica-cfb\/","title":{"rendered":"19\u00aa Gest\u00e3o do CFB lan\u00e7a \u201cBiblioteca na Escola e a Lei 12.244\/2010: mapeamento da produ\u00e7\u00e3o cient\u00edfica e acad\u00eamica\u201d \/ CFB"},"content":{"rendered":"\n<p><strong>19\u00aa Gest\u00e3o do CFB lan\u00e7a \u201cBiblioteca na Escola e a Lei 12.244\/2010: mapeamento da produ\u00e7\u00e3o cient\u00edfica e acad\u00eamica\u201d<\/strong><\/p>\n\n\n\n<p>Dispon\u00edvel em vers\u00e3o impressa e digital, o livro pode ser acessado gratuitamente no reposit\u00f3rio oficial do CFB, refor\u00e7ando o compromisso do conselho com a amplia\u00e7\u00e3o do acesso \u00e0 informa\u00e7\u00e3o. Maria de Lourdes concluiu o evento com uma mensagem inspiradora: \u201cEste livro n\u00e3o \u00e9 apenas sobre bibliotecas escolares; ele \u00e9 sobre a nossa capacidade de transformar a realidade por meio da uni\u00e3o de esfor\u00e7os. Ele \u00e9 sobre educa\u00e7\u00e3o, sobre cidadania e sobre o futuro que queremos construir.\u201d<\/p>\n\n\n\n<p>#BibliotecasEscolares #Lei12244\/2010<\/p>\n\n\n\n<p>via CFB<\/p>\n\n\n\n<p>Dispon\u00edvel em: <a href=\"https:\/\/cfb.org.br\/noticias\/19a-gestao-do-cfb-lanca-biblioteca-na-escola-e-a-lei-12-244-2010-mapeamento-da-producao-cientifica-e-academica\/\">https:\/\/cfb.org.br\/noticias\/19a-gestao-do-cfb-lanca-biblioteca-na-escola-e-a-lei-12-244-2010-mapeamento-da-producao-cientifica-e-academica\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>19\u00aa Gest\u00e3o do CFB lan\u00e7a \u201cBiblioteca na Escola e a Lei 12.244\/2010: mapeamento da produ\u00e7\u00e3o cient\u00edfica e acad\u00eamica\u201d Dispon\u00edvel em vers\u00e3o impressa e digital, o livro pode ser acessado gratuitamente no reposit\u00f3rio oficial do CFB, refor\u00e7ando o compromisso do conselho com a amplia\u00e7\u00e3o do acesso \u00e0 informa\u00e7\u00e3o. Maria de Lourdes concluiu o evento com uma<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/www.pedroandretta.info\/index\/2025\/01\/19a-gestao-do-cfb-lanca-biblioteca-na-escola-e-a-lei-12-244-2010-mapeamento-da-producao-cientifica-e-academica-cfb\/\" class=\"home-blog-btn\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[79,884],"class_list":["post-28833","post","type-post","status-publish","format-standard","hentry","category-informeci","tag-bibliotecasescolares","tag-lei12244"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","views":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/28833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/comments?post=28833"}],"version-history":[{"count":0,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/28833\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/media?parent=28833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/categories?post=28833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/tags?post=28833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}