{"id":30809,"date":"2025-05-13T15:24:01","date_gmt":"2025-05-13T19:24:01","guid":{"rendered":"https:\/\/www.pedroandretta.info\/index\/?p=30809"},"modified":"2025-05-13T15:24:06","modified_gmt":"2025-05-13T19:24:06","slug":"bibliotecas-de-universidades-federais-da-amazonia-brasileira-contribuicoes-ao-desenvolvimento-sustentavel-encontros-bibli","status":"publish","type":"post","link":"https:\/\/www.pedroandretta.info\/index\/2025\/05\/bibliotecas-de-universidades-federais-da-amazonia-brasileira-contribuicoes-ao-desenvolvimento-sustentavel-encontros-bibli\/","title":{"rendered":"Bibliotecas de universidades federais da Amaz\u00f4nia brasileira: contribui\u00e7\u00f5es ao desenvolvimento sustent\u00e1vel \/ Encontros Bibli"},"content":{"rendered":"\n<p><strong>Bibliotecas de universidades federais da Amaz\u00f4nia brasileira: contribui\u00e7\u00f5es ao desenvolvimento sustent\u00e1vel<\/strong><\/p>\n\n\n\n<p>O estudo destaca como as bibliotecas democratizam o acesso p\u00fablico \u00e0 informa\u00e7\u00e3o, promovem a alfabetiza\u00e7\u00e3o e a compet\u00eancia informacional, incentivam a cidadania consciente e contribuem para a transforma\u00e7\u00e3o da realidade e melhoria das condi\u00e7\u00f5es de vida. Tamb\u00e9m mostra que, ao participar da gest\u00e3o da comunica\u00e7\u00e3o cient\u00edfica, as bibliotecas apoiam a pesquisa, o desenvolvimento tecnol\u00f3gico e inova\u00e7\u00f5es que beneficiam o desenvolvimento social e promovem uma educa\u00e7\u00e3o inclusiva, equitativa e de qualidade.<\/p>\n\n\n\n<p>#BibliotecasUniversit\u00e1ria #Amaz\u00f4nia #Sustentabilidade<\/p>\n\n\n\n<p>via Encontros Bibli<\/p>\n\n\n\n<p>Dispon\u00edvel em: <a href=\"https:\/\/periodicos.ufsc.br\/index.php\/eb\/article\/view\/102003\">https:\/\/periodicos.ufsc.br\/index.php\/eb\/article\/view\/102003<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"425\" height=\"600\" src=\"https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2025\/05\/image-57.png?resize=425%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-30810\" srcset=\"https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2025\/05\/image-57.png?resize=425%2C600&amp;ssl=1 425w, https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2025\/05\/image-57.png?resize=213%2C300&amp;ssl=1 213w, https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2025\/05\/image-57.png?w=550&amp;ssl=1 550w\" sizes=\"(max-width: 425px) 100vw, 425px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Bibliotecas de universidades federais da Amaz\u00f4nia brasileira: contribui\u00e7\u00f5es ao desenvolvimento sustent\u00e1vel O estudo destaca como as bibliotecas democratizam o acesso p\u00fablico \u00e0 informa\u00e7\u00e3o, promovem a alfabetiza\u00e7\u00e3o e a compet\u00eancia informacional, incentivam a cidadania consciente e contribuem para a transforma\u00e7\u00e3o da realidade e melhoria das condi\u00e7\u00f5es de vida. Tamb\u00e9m mostra que, ao participar da gest\u00e3o da<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/www.pedroandretta.info\/index\/2025\/05\/bibliotecas-de-universidades-federais-da-amazonia-brasileira-contribuicoes-ao-desenvolvimento-sustentavel-encontros-bibli\/\" class=\"home-blog-btn\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[971,114,40],"class_list":["post-30809","post","type-post","status-publish","format-standard","hentry","category-informeci","tag-amazonia","tag-bibliotecasuniversitarias","tag-sustentabilidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","views":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/30809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/comments?post=30809"}],"version-history":[{"count":0,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/30809\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/media?parent=30809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/categories?post=30809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/tags?post=30809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}