{"id":35673,"date":"2026-02-03T22:46:49","date_gmt":"2026-02-04T02:46:49","guid":{"rendered":"https:\/\/www.pedroandretta.info\/index\/?p=35673"},"modified":"2026-02-03T22:46:53","modified_gmt":"2026-02-04T02:46:53","slug":"o-impacto-das-bibliotecas-publicas-canadenses-canadian-urban-libraries-council","status":"publish","type":"post","link":"https:\/\/www.pedroandretta.info\/index\/2026\/02\/o-impacto-das-bibliotecas-publicas-canadenses-canadian-urban-libraries-council\/","title":{"rendered":"O impacto das bibliotecas p\u00fablicas canadenses \/ Canadian Urban Libraries Council"},"content":{"rendered":"\n<p><strong>O impacto das bibliotecas p\u00fablicas canadenses \/ Canadian Urban Libraries Council<\/strong><\/p>\n\n\n\n<p>Este projeto de pesquisa pioneiro no Canad\u00e1 visa aprofundar a compreens\u00e3o do papel social e comunit\u00e1rio das bibliotecas p\u00fablicas urbanas. Analisa como os servi\u00e7os, espa\u00e7os, programas e atividades das bibliotecas influenciam a vida das pessoas e o tecido social das comunidades, indo al\u00e9m de m\u00e9tricas tradicionais como o n\u00famero de visitas, empr\u00e9stimos de livros ou participa\u00e7\u00e3o em eventos. O estudo explora o valor que as bibliotecas geram em termos de bem-estar social, inclus\u00e3o, aprendizagem, coes\u00e3o comunit\u00e1ria e engajamento c\u00edvico.<\/p>\n\n\n\n<p>#ImpactoDasBibliotecas<\/p>\n\n\n\n<p>Dispon\u00edvel em: <a href=\"https:\/\/culc.ca\/wp-content\/uploads\/2026\/01\/Social-Impact-Study-in-English-2026-2.pdf\">https:\/\/culc.ca\/wp-content\/uploads\/2026\/01\/Social-Impact-Study-in-English-2026-2.pdf<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"600\" height=\"401\" src=\"https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2026\/02\/image-11.png?resize=600%2C401&#038;ssl=1\" alt=\"\" class=\"wp-image-35674\" srcset=\"https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2026\/02\/image-11.png?resize=600%2C401&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2026\/02\/image-11.png?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2026\/02\/image-11.png?resize=768%2C513&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2026\/02\/image-11.png?w=1092&amp;ssl=1 1092w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O impacto das bibliotecas p\u00fablicas canadenses \/ Canadian Urban Libraries Council Este projeto de pesquisa pioneiro no Canad\u00e1 visa aprofundar a compreens\u00e3o do papel social e comunit\u00e1rio das bibliotecas p\u00fablicas urbanas. Analisa como os servi\u00e7os, espa\u00e7os, programas e atividades das bibliotecas influenciam a vida das pessoas e o tecido social das comunidades, indo al\u00e9m de<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/www.pedroandretta.info\/index\/2026\/02\/o-impacto-das-bibliotecas-publicas-canadenses-canadian-urban-libraries-council\/\" class=\"home-blog-btn\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[3301],"class_list":["post-35673","post","type-post","status-publish","format-standard","hentry","category-informeci","tag-impactodasbibliotecas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","views":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/35673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/comments?post=35673"}],"version-history":[{"count":1,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/35673\/revisions"}],"predecessor-version":[{"id":35675,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/35673\/revisions\/35675"}],"wp:attachment":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/media?parent=35673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/categories?post=35673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/tags?post=35673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}