{"id":38206,"date":"2026-05-12T19:57:31","date_gmt":"2026-05-12T23:57:31","guid":{"rendered":"https:\/\/www.pedroandretta.info\/index\/?p=38206"},"modified":"2026-05-12T19:57:33","modified_gmt":"2026-05-12T23:57:33","slug":"bibliotecas-rag-o-que-fazem-e-qual-usar-shailey-dash","status":"publish","type":"post","link":"https:\/\/www.pedroandretta.info\/index\/2026\/05\/bibliotecas-rag-o-que-fazem-e-qual-usar-shailey-dash\/","title":{"rendered":"Bibliotecas RAG \u2014 O que fazem e qual usar? \/ Shailey Dash"},"content":{"rendered":"\n<p><strong>Bibliotecas RAG \u2014 O que fazem e qual usar? \/ Shailey Dash<\/strong><\/p>\n\n\n\n<p>Entender o que \u00e9 RAG, pelo menos em linhas gerais, \u00e9 relativamente f\u00e1cil. As coisas se complicam quando voc\u00ea tenta descobrir como executar um projeto piloto e qual das muitas bibliotecas RAG dispon\u00edveis usar. Primeiro, existem muitas: Langchain, Haystack, LlamaIndex e muitas outras. H\u00e1 tamb\u00e9m bibliotecas para bancos de dados vetoriais, como FAISS (Facebook AI Similarity Search), Elasticsearch e Milvus, entre outras. Como tudo isso funciona? Parece tudo muito complexo!<\/p>\n\n\n\n<p>#RAG #Chatbots <\/p>\n\n\n\n<p>via Shailey Dash<\/p>\n\n\n\n<p>Dispon\u00edvel em: <a href=\"https:\/\/medium.com\/@shaileydash\/rag-libraries-what-do-they-do-and-which-one-to-use-part-1-fe26d3c04121\">https:\/\/medium.com\/@shaileydash\/rag-libraries-what-do-they-do-and-which-one-to-use-part-1-fe26d3c04121<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"600\" height=\"353\" src=\"https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2026\/05\/image-49.png?resize=600%2C353&#038;ssl=1\" alt=\"\" class=\"wp-image-38207\" srcset=\"https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2026\/05\/image-49.png?resize=600%2C353&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2026\/05\/image-49.png?resize=300%2C176&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2026\/05\/image-49.png?resize=768%2C452&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.pedroandretta.info\/index\/wp-content\/uploads\/2026\/05\/image-49.png?w=1100&amp;ssl=1 1100w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Bibliotecas RAG \u2014 O que fazem e qual usar? \/ Shailey Dash Entender o que \u00e9 RAG, pelo menos em linhas gerais, \u00e9 relativamente f\u00e1cil. As coisas se complicam quando voc\u00ea tenta descobrir como executar um projeto piloto e qual das muitas bibliotecas RAG dispon\u00edveis usar. Primeiro, existem muitas: Langchain, Haystack, LlamaIndex e muitas outras.<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/www.pedroandretta.info\/index\/2026\/05\/bibliotecas-rag-o-que-fazem-e-qual-usar-shailey-dash\/\" class=\"home-blog-btn\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[21],"tags":[77,4208],"class_list":["post-38206","post","type-post","status-publish","format-standard","hentry","category-informeci","tag-chatbots","tag-rag"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","views":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/38206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/comments?post=38206"}],"version-history":[{"count":1,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/38206\/revisions"}],"predecessor-version":[{"id":38208,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/posts\/38206\/revisions\/38208"}],"wp:attachment":[{"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/media?parent=38206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/categories?post=38206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedroandretta.info\/index\/wp-json\/wp\/v2\/tags?post=38206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}